{"id":807,"date":"2022-01-11T18:10:06","date_gmt":"2022-01-11T18:10:06","guid":{"rendered":"https:\/\/soporte.revolutionsoft.net\/?post_type=knowledge_base&#038;p=807"},"modified":"2023-04-12T11:28:28","modified_gmt":"2023-04-12T11:28:28","slug":"licencia-server-evaluacion","status":"publish","type":"knowledge_base","link":"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/licencia-server-evaluacion\/","title":{"rendered":"C\u00f3mo activar una licencia de Windows Server en una versi\u00f3n de evaluaci\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Si tiene instalada la&nbsp;versi\u00f3n&nbsp;de&nbsp;Evaluaci\u00f3n&nbsp;no puede activarla con una licencia hasta que no pase a la versi\u00f3n comercial. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay que usar un comando&nbsp;DISM&nbsp;para \u00abconvertir\u00bb la licencia de&nbsp;evaluaci\u00f3n&nbsp;en una Standard (o Datacenter seg\u00fan la licencia adquirida).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez hecho esto, windows procede a \u00abeliminar\u00bb la marca de&nbsp;evaluaci\u00f3n&nbsp;y ya queda licenciado.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ello puedo hacerlo siguiendo estas instrucciones:&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Primero comprobar&nbsp; que&nbsp;versi\u00f3n&nbsp;tiene instalada:<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>DISM&nbsp;\/online \/Get-CurrentEdition<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Y si es la StandardEval activar mediante este comando:<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>DISM&nbsp;\/online \/Set-Edition:ServerStandard \/ProductKey:XXXXX-XXXXX-XXXXX-XXXXX-XXXXX \/AcceptEula<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si es la versi\u00f3n DatacenterEval activar mediante el siguiente comando:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><meta charset=\"utf-8\"><em>DISM&nbsp;\/online \/Set-Edition:ServerDatacenter \/ProductKey:XXXXX-XXXXX-XXXXX-XXXXX-XXXXX \/AcceptEula<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si tiene instalada la&nbsp;versi\u00f3n&nbsp;de&nbsp;Evaluaci\u00f3n&nbsp;no puede activarla con una licencia hasta que no pase a la versi\u00f3n comercial. Hay que usar un comando&nbsp;DISM&nbsp;para \u00abconvertir\u00bb la licencia de&nbsp;evaluaci\u00f3n&nbsp;en una Standard (o Datacenter seg\u00fan la licencia adquirida).&nbsp; Una vez hecho esto, windows procede a \u00abeliminar\u00bb la marca de&nbsp;evaluaci\u00f3n&nbsp;y ya queda licenciado.&nbsp; Para ello puedo hacerlo siguiendo estas instrucciones:&nbsp; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"template":"","format":"standard","kbg_category":[34],"kbg_tags":[],"class_list":["post-807","knowledge_base","type-knowledge_base","status-publish","format-standard","hentry","kbg_category-windows"],"kbg_buddy_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"kbg-a":false,"kbg-a-sid":false,"kbg-b":false,"kbg-b-sid":false,"kbg-tax-a":false,"kbg-tax-b":false,"kbg-tax-c":false,"kbg-tax-d":false,"kbg-tax-e":false,"kbg-single-post-1":false,"kbg-single-page-1":false,"kbg-contact-icon":false,"kbg-contact-image-small":false,"kbg-contact-image":false,"kbg-search-icon":false,"kbg-category-list-icon":false},"kbg_buddy_meta":{"settings":"inherit","layout":"1","sidebar":{"position":"left","classic":"kbg_sidebar_default","sticky":"kbg_sidebar_default_sticky"},"0":""},"kbg_buddy_meta_inherit":{"settings":"inherit","layout":"1","sidebar":{"position":"left","classic":"kbg_sidebar_default","sticky":"kbg_sidebar_default_sticky"}},"kbg_buddy_sidebars":{"none":"None","kbg_sidebar_default":"Default Sidebar","kbg_sidebar_default_sticky":"Default Sticky Sidebar","kbg_search_sidebar_default":"Search Archive Sidebar","kbg_search_sidebar_default_sticky":"Search Archive Sticky Sidebar"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo activar una licencia de Windows Server en una versi\u00f3n de evaluaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Aprende c\u00f3mo descargar, instalar y activar la licencia de servidor de evaluaci\u00f3n de Windows Server con este tutorial paso a paso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/licencia-server-evaluacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo activar una licencia de Windows Server en una versi\u00f3n de evaluaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Aprende c\u00f3mo descargar, instalar y activar la licencia de servidor de evaluaci\u00f3n de Windows Server con este tutorial paso a paso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/licencia-server-evaluacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Revolution Soft - Soporte\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-12T11:28:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/licencia-server-evaluacion\/\",\"url\":\"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/licencia-server-evaluacion\/\",\"name\":\"C\u00f3mo activar una licencia de Windows Server en una versi\u00f3n de evaluaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/soporte.revolutionsoft.net\/#website\"},\"datePublished\":\"2022-01-11T18:10:06+00:00\",\"dateModified\":\"2023-04-12T11:28:28+00:00\",\"description\":\"Aprende c\u00f3mo descargar, instalar y activar la licencia de servidor de evaluaci\u00f3n de Windows Server con este tutorial paso a paso.\",\"breadcrumb\":{\"@id\":\"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/licencia-server-evaluacion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/licencia-server-evaluacion\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/licencia-server-evaluacion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/soporte.revolutionsoft.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Knowledge Base\",\"item\":\"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo activar una licencia de Windows Server en una versi\u00f3n de evaluaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/soporte.revolutionsoft.net\/#website\",\"url\":\"https:\/\/soporte.revolutionsoft.net\/\",\"name\":\"Revolution Soft - Soporte\",\"description\":\"Soporte de Revolution Soft\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/soporte.revolutionsoft.net\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo activar una licencia de Windows Server en una versi\u00f3n de evaluaci\u00f3n","description":"Aprende c\u00f3mo descargar, instalar y activar la licencia de servidor de evaluaci\u00f3n de Windows Server con este tutorial paso a paso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/licencia-server-evaluacion\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo activar una licencia de Windows Server en una versi\u00f3n de evaluaci\u00f3n","og_description":"Aprende c\u00f3mo descargar, instalar y activar la licencia de servidor de evaluaci\u00f3n de Windows Server con este tutorial paso a paso.","og_url":"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/licencia-server-evaluacion\/","og_site_name":"Revolution Soft - Soporte","article_modified_time":"2023-04-12T11:28:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/licencia-server-evaluacion\/","url":"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/licencia-server-evaluacion\/","name":"C\u00f3mo activar una licencia de Windows Server en una versi\u00f3n de evaluaci\u00f3n","isPartOf":{"@id":"https:\/\/soporte.revolutionsoft.net\/#website"},"datePublished":"2022-01-11T18:10:06+00:00","dateModified":"2023-04-12T11:28:28+00:00","description":"Aprende c\u00f3mo descargar, instalar y activar la licencia de servidor de evaluaci\u00f3n de Windows Server con este tutorial paso a paso.","breadcrumb":{"@id":"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/licencia-server-evaluacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/licencia-server-evaluacion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/licencia-server-evaluacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/soporte.revolutionsoft.net\/"},{"@type":"ListItem","position":2,"name":"Knowledge Base","item":"https:\/\/soporte.revolutionsoft.net\/index.php\/knowledge-base\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo activar una licencia de Windows Server en una versi\u00f3n de evaluaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/soporte.revolutionsoft.net\/#website","url":"https:\/\/soporte.revolutionsoft.net\/","name":"Revolution Soft - Soporte","description":"Soporte de Revolution Soft","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soporte.revolutionsoft.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/soporte.revolutionsoft.net\/index.php\/wp-json\/wp\/v2\/knowledge_base\/807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soporte.revolutionsoft.net\/index.php\/wp-json\/wp\/v2\/knowledge_base"}],"about":[{"href":"https:\/\/soporte.revolutionsoft.net\/index.php\/wp-json\/wp\/v2\/types\/knowledge_base"}],"author":[{"embeddable":true,"href":"https:\/\/soporte.revolutionsoft.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/soporte.revolutionsoft.net\/index.php\/wp-json\/wp\/v2\/media?parent=807"}],"wp:term":[{"taxonomy":"kbg_category","embeddable":true,"href":"https:\/\/soporte.revolutionsoft.net\/index.php\/wp-json\/wp\/v2\/kbg_category?post=807"},{"taxonomy":"kbg_tags","embeddable":true,"href":"https:\/\/soporte.revolutionsoft.net\/index.php\/wp-json\/wp\/v2\/kbg_tags?post=807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}